{"id":3628891,"date":"2026-03-04T16:18:39","date_gmt":"2026-03-04T22:18:39","guid":{"rendered":"https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/"},"modified":"2026-08-19T02:08:15","modified_gmt":"2026-08-19T08:08:15","slug":"plasticos-makilgar-sa","status":"publish","type":"empresa","link":"https:\/\/directorio.export.com.gt\/en\/empresa\/plasticos-makilgar-sa\/","title":{"rendered":"PLASTICOS MAKILGAR, S.A."},"parent":0,"template":"","class_list":["post-3628891","empresa","type-empresa","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/directorio.export.com.gt\/en\/empresa\/plasticos-makilgar-sa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/directorio.export.com.gt\/en\/empresa\/plasticos-makilgar-sa\/\" \/>\n<meta property=\"og:site_name\" content=\"Directorio de Exportadores\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-19T08:08:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/plasticos-makilgar-sa\\\/\",\"url\":\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/plasticos-makilgar-sa\\\/\",\"name\":\"PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/directorio.export.com.gt\\\/#website\"},\"datePublished\":\"2026-03-04T22:18:39+00:00\",\"dateModified\":\"2026-08-19T08:08:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/plasticos-makilgar-sa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/plasticos-makilgar-sa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/plasticos-makilgar-sa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/directorio.export.com.gt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa\",\"item\":\"https:\\\/\\\/directorio.export.com.gt\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PLASTICOS MAKILGAR, S.A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/directorio.export.com.gt\\\/#website\",\"url\":\"https:\\\/\\\/directorio.export.com.gt\\\/\",\"name\":\"Directorio de Exportadores\",\"description\":\"Agexport\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/directorio.export.com.gt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/directorio.export.com.gt\/en\/empresa\/plasticos-makilgar-sa\/","og_locale":"en_US","og_type":"article","og_title":"PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores","og_url":"https:\/\/directorio.export.com.gt\/en\/empresa\/plasticos-makilgar-sa\/","og_site_name":"Directorio de Exportadores","article_modified_time":"2026-08-19T08:08:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/","url":"https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/","name":"PLASTICOS MAKILGAR, S.A. - Directorio de Exportadores","isPartOf":{"@id":"https:\/\/directorio.export.com.gt\/#website"},"datePublished":"2026-03-04T22:18:39+00:00","dateModified":"2026-08-19T08:08:15+00:00","breadcrumb":{"@id":"https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/directorio.export.com.gt\/empresa\/plasticos-makilgar-sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/directorio.export.com.gt\/"},{"@type":"ListItem","position":2,"name":"Empresa","item":"https:\/\/directorio.export.com.gt\/empresa\/"},{"@type":"ListItem","position":3,"name":"PLASTICOS MAKILGAR, S.A."}]},{"@type":"WebSite","@id":"https:\/\/directorio.export.com.gt\/#website","url":"https:\/\/directorio.export.com.gt\/","name":"Directorio de Exportadores","description":"Agexport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/directorio.export.com.gt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/directorio.export.com.gt\/en\/wp-json\/wp\/v2\/empresa\/3628891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/directorio.export.com.gt\/en\/wp-json\/wp\/v2\/empresa"}],"about":[{"href":"https:\/\/directorio.export.com.gt\/en\/wp-json\/wp\/v2\/types\/empresa"}],"wp:attachment":[{"href":"https:\/\/directorio.export.com.gt\/en\/wp-json\/wp\/v2\/media?parent=3628891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}